{"id":4245,"date":"2018-02-12T11:27:38","date_gmt":"2018-02-12T11:27:38","guid":{"rendered":"http:\/\/tortosaturisme-preprod.incubaliadev.com\/es\/el-mercat-de-tortosa\/"},"modified":"2020-07-23T10:37:19","modified_gmt":"2020-07-23T10:37:19","slug":"el-mercado-de-tortosa","status":"publish","type":"page","link":"https:\/\/www.tortosaturisme.cat\/es\/el-mercado-de-tortosa\/","title":{"rendered":"El Mercado de Tortosa"},"content":{"rendered":"<p>[vc_row][vc_column]<div class=\"vc-incubalia-big-header\"><h1 class=\"vc-incubalia-big-header__title\">El Mercado Municipal<\/h1><img decoding=\"async\" class=\"vc-incubalia-big-header__mobile-picture\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/1-mercat-fora-mb.jpg\">\n                  <img decoding=\"async\" class=\"vc-incubalia-big-header__desktop-picture\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/1-mercat-fora-ds.jpg\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vc-incubalia-text-1-column-subtitle\"><h2 class=\"vc-incubalia-text-1-column-subtitle__title\">El templo de la comida<\/h2><h3 class=\"vc-incubalia-text-1-column-subtitle__subtitle\">Un verdadero monumento por fuera y por dentro dedicado a los mejores productos<\/h3><div class=\"vc-incubalia-text-1-column-subtitle__text\"><\/p><br \/>\n<p style=\"text-align: center;\"><strong>La gastronom\u00eda rica y variada de las Tierras del Ebro<\/strong> y sus productos frescos se pueden encontrar casi todos, de una forma sencilla y c\u00f3moda, en un \u00fanico espacio: el mercado municipal de Tortosa. El mercado es<strong> un lugar ideal para encontrar la diversidad de productos gastron\u00f3micos del territorio<\/strong> con todas las garant\u00edas de calidad.<\/p><br \/>\n<p><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vc-incubalia-image-huge\"><img decoding=\"async\" class=\"vc-incubalia-image-huge__mobile-picture brightness-100\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/2-mercat-mb.jpg\" alt=\"\"><img decoding=\"async\" class=\"vc-incubalia-image-huge__desktop-picture brightness-100\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/2-mercat-ds.jpg\" alt=\"\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vc-incubalia-text-1-column-subtitle\"><div class=\"vc-incubalia-text-1-column-subtitle__text\"><\/p><br \/>\n<p>Recomendamos hacer un hueco en vuestra visita en el coraz\u00f3n de la ciudad para descubrir este\u00a0<b>emblem\u00e1tico\u00a0edificio modernista<\/b> por dentro. El mercado funciona como centro neur\u00e1lgico y se encuentra en el mismo centro de la Avinguda Generalitat, rodeado de comercios y establecimientos donde completar la visita. Solamente desde el exterior es ya un espect\u00e1culo, siendo un imponente edificio obra de<strong> Joan Abril\u00a0<\/strong>y\u00a0<strong>Joan Torras<\/strong>, junto al que se encuentra una plaza con terrazas donde poder disfrutar del sol del mediod\u00eda o pararnos a descansar.<\/p><br \/>\n<p><\/div><\/div><div class=\"vc-incubalia-text-image-full\"><div class=\"vc-incubalia-text-image-full__image-container\"><img decoding=\"async\" class=\"vc-incubalia-text-image-full__image-mobile\" alt=\"\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/3-mercat-mb.jpg\"><img decoding=\"async\" class=\"vc-incubalia-text-image-full__image-desktop\" alt=\"\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/3-mercat-ds.jpg\"><i class=\"arrow-down\"><\/i><\/div><div class=\"vc-incubalia-text-image-full__text-container\"><div class=\"vc-incubalia-text-image-full__text\"><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vc-incubalia-text-1-column-subtitle\"><div class=\"vc-incubalia-text-1-column-subtitle__text\"><\/p><br \/>\n<p style=\"text-align: center;\">En su interior, encontraremos <b>una amplia\u00a0oferta de puestos<\/b> con carnicer\u00edas, fruter\u00edas, panader\u00edas, charcuter\u00edas, bacallaners (puntos de venta de bacalao) y una selecci\u00f3n de conservas y <strong>productos del territorio<\/strong>, as\u00ed como establecimientos donde desayunar o comer en medio de un ambiente lleno de la vida, el murmullo y el color que siempre se genera alrededor de un mercado. Los vendedores son personas muy cercanas, algunos de los cuales han dedicado toda\u00a0 su vida a su puesto en el mercado, y podr\u00e1n ofrecernos los productos acabados de llegar con toda una historia a sus espaldas.<\/p><br \/>\n<p><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vc-incubalia-3-images\"><h2 class=\"vc-incubalia-3-images__title\">Organ\u00edzate<\/h2><div class=\"vc-incubalia-3-images__image\"><a href=\"\/es\/restaurantes\/\"><img decoding=\"async\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/b-800-exp-pacs.jpg\" alt=\"\"><\/a><a href=\"\/es\/restaurantes\/\"><p class=\"vc-incubalia-3-images__image-title\">Restaurantes<\/p><\/a><p class=\"vc-incubalia-3-images__image-subtitle\">Una cocina arraigada a la tierra que saca partido de los productos de proximidad, pero tambi\u00e9n abierta a las nueves tendencias. En Tortosa encontrar\u00e1s una cocina de mercado, pero tambi\u00e9n internacional y mediterr\u00e1nea<\/p><\/div><div class=\"vc-incubalia-3-images__image\"><a href=\"\/es\/alojamientos\/\"><img decoding=\"async\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/b-800-allotjaments.jpg\" alt=\"\"><\/a><a href=\"\/es\/alojamientos\/\"><p class=\"vc-incubalia-3-images__image-title\">Alojamientos<\/p><\/a><p class=\"vc-incubalia-3-images__image-subtitle\">Tortosa te ofrece alojamientos de todo tipo. Duerme en un castillo, casas rurales rodeadas de naturaleza, hoteles con todas las comodidades o apartamentos en el coraz\u00f3n de la ciudad antigua<\/p><\/div><div class=\"vc-incubalia-3-images__image\"><a href=\"\/es\/experiencias\/\"><img decoding=\"async\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/b-800-via-verda.jpg\" alt=\"\"><\/a><a href=\"\/es\/experiencias\/\"><p class=\"vc-incubalia-3-images__image-title\">Experiencias<\/p><\/a><p class=\"vc-incubalia-3-images__image-subtitle\">Completa tu visita con una oferta de experiencias de todo tipo: excursionismo, visites guiadas, navegaciones...<\/p><\/div><\/div><div class=\"vc-incubalia-5-cards\"><h2 class=\"vc-incubalia-5-cards__title\">Te recomendamos<\/h2><div class=\"vc-incubalia-5-cards__card card-1 has-url\"><a href=\"\/es\/tortosa-en-un-dia\/\"><img decoding=\"async\" class=\"vc-incubalia-5-cards__card-mobile-picture\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/B-1280-ruta-ren-640x460.jpg\">\n                      <img decoding=\"async\" class=\"vc-incubalia-5-cards__card-desktop-picture\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/B-1280-ruta-ren.jpg\"><\/a><div class=\"vc-incubalia-5-cards__card-text-container\"><p class=\"vc-incubalia-5-cards__card-title\">Tortosa en un d\u00eda<\/p><\/div><div class=\"vc-incubalia-5-cards__card-url-container\"><span class=\"vc-incubalia-5-cards__card-url\">Leer m\u00e1s<\/span><\/div><\/div><div class=\"vc-incubalia-5-cards__card card-2 has-url\"><a href=\"\/es\/jornadas-gastronomicas\/\"><img decoding=\"async\" class=\"vc-incubalia-5-cards__card-mobile-picture\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/B-1280-mercat-640x460.jpg\">\n                      <img decoding=\"async\" class=\"vc-incubalia-5-cards__card-desktop-picture\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/B-1280-mercat-640x460.jpg\"><\/a><div class=\"vc-incubalia-5-cards__card-text-container\"><p class=\"vc-incubalia-5-cards__card-title\">Jornadas gastron\u00f3micas <\/p><\/div><div class=\"vc-incubalia-5-cards__card-url-container\"><span class=\"vc-incubalia-5-cards__card-url\">Leer m\u00e1s<\/span><\/div><\/div><div class=\"vc-incubalia-5-cards__card-3-and-4-container\"><div class=\"vc-incubalia-5-cards__card card-3 has-url\"><a href=\"\/es\/la-cocina-de-las-tierras-del-ebro\/\"><img decoding=\"async\" class=\"vc-incubalia-5-cards__card-mobile-picture\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/b-1280-cuina-terres-640x460.jpg\">\n                      <img decoding=\"async\" class=\"vc-incubalia-5-cards__card-desktop-picture\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/b-1280-cuina-terres-640x460.jpg\"><\/a><div class=\"vc-incubalia-5-cards__card-text-container\"><p class=\"vc-incubalia-5-cards__card-title\">La cocina de las Tierras del Ebro<\/p><\/div><div class=\"vc-incubalia-5-cards__card-url-container\"><span class=\"vc-incubalia-5-cards__card-url\">Leer m\u00e1s<\/span><\/div><\/div><div class=\"vc-incubalia-5-cards__card card-4 has-url\"><a href=\"\/es\/lo-mejor-de-la-tierra\/\"><img decoding=\"async\" class=\"vc-incubalia-5-cards__card-mobile-picture\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/1280-b-el-millor-de-la-terra-640x460.jpg\">\n                      <img decoding=\"async\" class=\"vc-incubalia-5-cards__card-desktop-picture\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/1280-b-el-millor-de-la-terra-640x460.jpg\"><\/a><div class=\"vc-incubalia-5-cards__card-text-container\"><p class=\"vc-incubalia-5-cards__card-title\">Los mejores productos de la tierra <\/p><p class=\"vc-incubalia-5-cards__card-subtitle\">Un territorio exuberante, de arrozales, vi\u00f1a, naranjos y olivos<\/p><\/div><div class=\"vc-incubalia-5-cards__card-url-container\"><span class=\"vc-incubalia-5-cards__card-url\">Leer m\u00e1s<\/span><\/div><\/div><\/div><div class=\"vc-incubalia-5-cards__card card-5 has-url\"><a href=\"\/es\/lo-mejor-del-mar\/\"><img decoding=\"async\" class=\"vc-incubalia-5-cards__card-mobile-picture\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/b-1280-el-millor-de-la-mar-d-640x460.jpg\">\n                      <img decoding=\"async\" class=\"vc-incubalia-5-cards__card-desktop-picture\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/b-1280-el-millor-de-la-mar-d-640x449.jpg\"><\/a><div class=\"vc-incubalia-5-cards__card-text-container\"><p class=\"vc-incubalia-5-cards__card-title\">Lo mejor del mar<\/p><p class=\"vc-incubalia-5-cards__card-subtitle\">Disfruta de la riqueza del mar mediterr\u00e1neo<\/p><\/div><div class=\"vc-incubalia-5-cards__card-url-container\"><span class=\"vc-incubalia-5-cards__card-url\">Leer m\u00e1s<\/span><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vc-incubalia-3-images\"><h2 class=\"vc-incubalia-3-images__title\">Te proponemos<\/h2><div class=\"vc-incubalia-3-images__image\"><a href=\"\/es\/experiencias\/?experience-type=packs-turistics-es&list-view=cards\"><img decoding=\"async\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/b-800-allotjament.jpg\" alt=\"\"><\/a><a href=\"\/es\/experiencias\/?experience-type=packs-turistics-es&list-view=cards\"><p class=\"vc-incubalia-3-images__image-title\">Experiencias completas<\/p><\/a><p class=\"vc-incubalia-3-images__image-subtitle\">Combina la gastronom\u00eda y las actividades alrededor de la ciudad y la naturaleza<\/p><\/div><div class=\"vc-incubalia-3-images__image\"><a href=\"\/es\/experiencias\/?experience-type=navegacio-es&list-view=cards\"><img decoding=\"async\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/B-800-navega.jpg\" alt=\"\"><\/a><a href=\"\/es\/experiencias\/?experience-type=navegacio-es&list-view=cards\"><p class=\"vc-incubalia-3-images__image-title\">Navegaci\u00f3n<\/p><\/a><p class=\"vc-incubalia-3-images__image-subtitle\">Recorre el Ebro con Lo Sirgador, hech\u00edzate con les puestas de sol, prueba los vinos de la Tierra o disfruta de evocadores conciertos a bordo<\/p><\/div><div class=\"vc-incubalia-3-images__image\"><a href=\"\/es\/experiencias\/?experience-type=gastronomiques-es&list-view=cards\"><img decoding=\"async\" src=\"https:\/\/www.tortosaturisme.cat\/wp-content\/uploads\/2018\/02\/b-800-experiencies-gastronomiques-d.jpg\" alt=\"\"><\/a><a href=\"\/es\/experiencias\/?experience-type=gastronomiques-es&list-view=cards\"><p class=\"vc-incubalia-3-images__image-title\">Jornadas gastron\u00f3micas<\/p><\/a><p class=\"vc-incubalia-3-images__image-subtitle\">Para los paladares m\u00e1s exigentes<\/p><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":338,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4245","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Mercado Municipal, el templo de la comida - Tortosa Turisme<\/title>\n<meta name=\"description\" content=\"Erigido como una verdadera obra de arte por dentro y por fuera, creado por los arquitectos Joan Abril y Joan Torras, el Mercado Municipal de Tortosa es una parada obligada para los amantes de la arquitectura modernista y la comida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tortosaturisme.cat\/es\/el-mercado-de-tortosa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Mercado Municipal, el templo de la comida - Tortosa Turisme\" \/>\n<meta property=\"og:description\" content=\"Erigido como una verdadera obra de arte por dentro y por fuera, creado por los arquitectos Joan Abril y Joan Torras, el Mercado Municipal de Tortosa es una parada obligada para los amantes de la arquitectura modernista y la comida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tortosaturisme.cat\/es\/el-mercado-de-tortosa\/\" \/>\n<meta property=\"og:site_name\" content=\"tortosaturisme\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-23T10:37:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tortosaturisme.cat\\\/es\\\/el-mercado-de-tortosa\\\/\",\"url\":\"https:\\\/\\\/www.tortosaturisme.cat\\\/es\\\/el-mercado-de-tortosa\\\/\",\"name\":\"El Mercado Municipal, el templo de la comida - Tortosa Turisme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tortosaturisme.cat\\\/es\\\/#website\"},\"datePublished\":\"2018-02-12T11:27:38+00:00\",\"dateModified\":\"2020-07-23T10:37:19+00:00\",\"description\":\"Erigido como una verdadera obra de arte por dentro y por fuera, creado por los arquitectos Joan Abril y Joan Torras, el Mercado Municipal de Tortosa es una parada obligada para los amantes de la arquitectura modernista y la comida.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tortosaturisme.cat\\\/es\\\/el-mercado-de-tortosa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tortosaturisme.cat\\\/es\\\/el-mercado-de-tortosa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tortosaturisme.cat\\\/es\\\/el-mercado-de-tortosa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tortosaturisme.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Mercado de Tortosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tortosaturisme.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.tortosaturisme.cat\\\/es\\\/\",\"name\":\"tortosaturisme\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tortosaturisme.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Mercado Municipal, el templo de la comida - Tortosa Turisme","description":"Erigido como una verdadera obra de arte por dentro y por fuera, creado por los arquitectos Joan Abril y Joan Torras, el Mercado Municipal de Tortosa es una parada obligada para los amantes de la arquitectura modernista y la comida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tortosaturisme.cat\/es\/el-mercado-de-tortosa\/","og_locale":"es_ES","og_type":"article","og_title":"El Mercado Municipal, el templo de la comida - Tortosa Turisme","og_description":"Erigido como una verdadera obra de arte por dentro y por fuera, creado por los arquitectos Joan Abril y Joan Torras, el Mercado Municipal de Tortosa es una parada obligada para los amantes de la arquitectura modernista y la comida.","og_url":"https:\/\/www.tortosaturisme.cat\/es\/el-mercado-de-tortosa\/","og_site_name":"tortosaturisme","article_modified_time":"2020-07-23T10:37:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tortosaturisme.cat\/es\/el-mercado-de-tortosa\/","url":"https:\/\/www.tortosaturisme.cat\/es\/el-mercado-de-tortosa\/","name":"El Mercado Municipal, el templo de la comida - Tortosa Turisme","isPartOf":{"@id":"https:\/\/www.tortosaturisme.cat\/es\/#website"},"datePublished":"2018-02-12T11:27:38+00:00","dateModified":"2020-07-23T10:37:19+00:00","description":"Erigido como una verdadera obra de arte por dentro y por fuera, creado por los arquitectos Joan Abril y Joan Torras, el Mercado Municipal de Tortosa es una parada obligada para los amantes de la arquitectura modernista y la comida.","breadcrumb":{"@id":"https:\/\/www.tortosaturisme.cat\/es\/el-mercado-de-tortosa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tortosaturisme.cat\/es\/el-mercado-de-tortosa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tortosaturisme.cat\/es\/el-mercado-de-tortosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tortosaturisme.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El Mercado de Tortosa"}]},{"@type":"WebSite","@id":"https:\/\/www.tortosaturisme.cat\/es\/#website","url":"https:\/\/www.tortosaturisme.cat\/es\/","name":"tortosaturisme","description":"Otro sitio realizado con WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tortosaturisme.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tortosaturisme.cat\/es\/wp-json\/wp\/v2\/pages\/4245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tortosaturisme.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tortosaturisme.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tortosaturisme.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tortosaturisme.cat\/es\/wp-json\/wp\/v2\/comments?post=4245"}],"version-history":[{"count":0,"href":"https:\/\/www.tortosaturisme.cat\/es\/wp-json\/wp\/v2\/pages\/4245\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tortosaturisme.cat\/es\/wp-json\/wp\/v2\/media?parent=4245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}